{"id":998,"date":"2021-08-31T11:46:41","date_gmt":"2021-08-31T09:46:41","guid":{"rendered":"http:\/\/dgg-ev-bonn.de\/?p=998"},"modified":"2021-08-31T11:52:41","modified_gmt":"2021-08-31T09:52:41","slug":"17-september-empfehlung-fuer-online-seminar-medien-zwischen-sexismus-und-feminismus","status":"publish","type":"post","link":"http:\/\/dgg-ev-bonn.de\/index.php\/2021\/08\/31\/17-september-empfehlung-fuer-online-seminar-medien-zwischen-sexismus-und-feminismus\/","title":{"rendered":"17. September &#8211; Empfehlung f\u00fcr ONLINE-Seminar &#8222;Medien zwischen Sexismus und Feminismus&#8220;"},"content":{"rendered":"\n<p>In den Medien herrscht ein Ungleichgewicht, wenn es um Geschlechter geht \u2013 und das hat Auswirkungen. Wirtschaftsthemen werden haupts\u00e4chlich von M\u00e4nnern f\u00fcr M\u00e4nner gemacht, Lifestyle-Themen von Frauen f\u00fcr Frauen. Dass Medien Wirklichkeit aufnehmen und ausspielen ist kein Geheimnis. Sich diesen Kreislauf bewusst zu machen, erfordert allerdings \u00dcbung. Wie werden Frauen auf Plakaten, in der Werbung oder in den sozialen Netzwerken dargestellt? Wie unterschwellig kann sich Sexismus in den Medien verbreiten und festigen? Und wo wird Feminismus schon aktiv gelebt?&nbsp;<\/p>\n\n\n\n<p>Die Reproduktion von Stereotypen in der Medienwelt zeigen wir aus feministischer Sicht auf \u2013&nbsp;<strong><a rel=\"noreferrer noopener\" href=\"http:\/\/277177.250603.seu2.cleverreach.com\/c\/62259346\/073671ad3e26-qynjxk\/Link%2CHomepage%2CWebsite%2CAnmeldung%2COnline-Seminar%2CMedien%2CFeminismus\" target=\"_blank\">im Online-Seminar am Freitag, 17. September, von 13 bis 15 Uhr<\/a><\/strong> ANMELDUNG: https:\/\/www.frankenwarte.de\/veranstaltungen\/online\/index.html?ev[id]=230<\/p>\n\n\n\n<p><strong>Unsere Referentinnen<\/strong>&nbsp;Elisabeth Ries und Luisa Filip besch\u00e4ftigen sich in&nbsp;<a href=\"http:\/\/277177.250603.seu2.cleverreach.com\/c\/62259347\/073671ad3e26-qynjxk\/Link%2CHomepage%2CWebsite%2CPodcast%2CMedien%2CFeminismus\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eX und Y &#8211; Der Podcast \u00fcber Medien und Feminismus\u201c<\/a>&nbsp;mit oben genannten Themen.&nbsp;<a href=\"http:\/\/277177.250603.seu2.cleverreach.com\/c\/62259348\/073671ad3e26-qynjxk\/Link%2CHomepage%2CWebsite%2CMedien%2CJournalismus\" target=\"_blank\" rel=\"noreferrer noopener\">Luisa Filip<\/a>&nbsp;ist freie Journalistin beim Deutschlandfunk und Podcast-Redakteurin,&nbsp;<a href=\"http:\/\/277177.250603.seu2.cleverreach.com\/c\/62259349\/073671ad3e26-qynjxk\/Link%2CHomepage%2CWebsite%2CProfil%2CLinkedIn%2CJournalistin%2CMedien%2CElisabeth+Ries\" target=\"_blank\" rel=\"noreferrer noopener\">Elisabeth Ries<\/a>&nbsp;ist ebenfalls Journalistin und hat sich zuletzt in ihrer Masterarbeit intensiv mit dem Thema \u201cFeminismus und Sexismus in den Medien\u201d besch\u00e4ftigt. In ihrem Vortrag geben sie einen Einblick in ihre Recherchen und werden zeigen, wie sich jede*r im eigenen Medienkonsum f\u00fcr Sexismus und Feminismus sensibilisieren kann (inklusive To-Go-Checkliste f\u00fcr die Teilnehmenden).<\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"http:\/\/277177.250603.seu2.cleverreach.com\/c\/62259350\/073671ad3e26-qynjxk\/Link%2CWebsite%2CHomepage%2CProgramm%2CFrankenwarte\" target=\"_blank\">Unser komplettes Programm finden Sie&nbsp;<strong>hier<\/strong>.<\/a>&nbsp;Wir freuen uns auf Ihre Teilnahme!<br>Mit den besten Gr\u00fc\u00dfen aus W\u00fcrzburg<\/p>\n\n\n\n<p>Wir unterst\u00fctzen das Team der Akademie Frankenwarte<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"http:\/\/dgg-ev-bonn.de\/wp-content\/uploads\/2021\/08\/2021-9-FraWar-Online-Sem-Medien.pdf\">2021-9-FraWar-Online-Sem-Medien<\/a><a href=\"http:\/\/dgg-ev-bonn.de\/wp-content\/uploads\/2021\/08\/2021-9-FraWar-Online-Sem-Medien.pdf\" class=\"wp-block-file__button\" download>Herunterladen<\/a><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den Medien herrscht ein Ungleichgewicht, wenn es um Geschlechter geht \u2013 und das hat Auswirkungen. Wirtschaftsthemen werden haupts\u00e4chlich von<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-998","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"http:\/\/dgg-ev-bonn.de\/index.php\/wp-json\/wp\/v2\/posts\/998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/dgg-ev-bonn.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/dgg-ev-bonn.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/dgg-ev-bonn.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/dgg-ev-bonn.de\/index.php\/wp-json\/wp\/v2\/comments?post=998"}],"version-history":[{"count":2,"href":"http:\/\/dgg-ev-bonn.de\/index.php\/wp-json\/wp\/v2\/posts\/998\/revisions"}],"predecessor-version":[{"id":1001,"href":"http:\/\/dgg-ev-bonn.de\/index.php\/wp-json\/wp\/v2\/posts\/998\/revisions\/1001"}],"wp:attachment":[{"href":"http:\/\/dgg-ev-bonn.de\/index.php\/wp-json\/wp\/v2\/media?parent=998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/dgg-ev-bonn.de\/index.php\/wp-json\/wp\/v2\/categories?post=998"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/dgg-ev-bonn.de\/index.php\/wp-json\/wp\/v2\/tags?post=998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}